{"id":4399,"date":"2025-12-03T20:24:17","date_gmt":"2025-12-03T20:24:17","guid":{"rendered":"https:\/\/paautos.gt\/inicio\/?page_id=4399"},"modified":"2025-12-11T19:42:36","modified_gmt":"2025-12-11T19:42:36","slug":"taller-zona-10","status":"publish","type":"page","link":"http:\/\/paautos.gt\/inicio\/nuestros-talleres\/taller-zona-10\/","title":{"rendered":"Taller Mec\u00e1nico Zona 10 &#8211; PaAutos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4399\" class=\"elementor elementor-4399\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af28b10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af28b10\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e920739\" data-id=\"e920739\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1eb3aae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1eb3aae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-324f238\" data-id=\"324f238\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f883bd2 elementor-widget elementor-widget-heading\" data-id=\"f883bd2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">PaAutos - Taller Mec\u00e1nico en Zona 10<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f3630c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f3630c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-92e89bf\" data-id=\"92e89bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0f1b11 elementor-widget elementor-widget-text-editor\" data-id=\"e0f1b11\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPaAutos Zona 10 es nuestro nuevo taller mec\u00e1nico y centro automotriz en Ciudad de Guatemala, dise\u00f1ado para ofrecer un servicio r\u00e1pido, eficiente y con la comodidad que necesitas. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8503613\" data-id=\"8503613\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2093192 elementor-widget elementor-widget-text-editor\" data-id=\"2093192\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contamos con instalaciones amplias, modernas y equipadas, ideales para que tu experiencia sea \u00e1gil y segura mientras realizamos el mantenimiento de tu veh\u00edculo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-83d545a e-flex e-con-boxed e-con e-parent\" data-id=\"83d545a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b044fb9 elementor-align-left elementor-widget__width-auto elementor-widget-mobile__width-auto elementor-icon-list--layout-inline elementor-mobile-align-left amenidades elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b044fb9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-wifi\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wifi gratis<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-car\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parqueo privado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-restroom\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sanitarios<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chair\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sala de espera<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-handshake\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Atenci\u00f3n personalizada<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47c8f03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47c8f03\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fc748a\" data-id=\"7fc748a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b85c6a elementor-widget elementor-widget-heading\" data-id=\"3b85c6a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informaci\u00f3n del taller<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ac00a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ac00a6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-627b782\" data-id=\"627b782\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce58c79 elementor-widget elementor-widget-text-editor\" data-id=\"ce58c79\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Horario de atenci\u00f3n<\/strong><\/h5>\n<p><strong>Lunes a Viernes: <\/strong>7:30 a 17:00 hrs.<br \/>\n<strong>S\u00e1bado:<\/strong> 7:30 a 15:00 hrs.<br \/>\n<strong>PBX:<\/strong> 2270-5757<\/p>\n<h5><strong>Direcci\u00f3n:<\/strong><\/h5>\n<p>18 avenida 20-82 zona 10, Ciudad de Guatemala<br \/>\nAntes de llegar a la estaci\u00f3n de polic\u00eda de la diagonal 6.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d5d843 elementor-align-left elementor-widget__width-auto elementor-mobile-align-center waze-btn elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"6d5d843\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-waze\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ir con Waze<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63c8041\" data-id=\"63c8041\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d779c9c elementor-widget elementor-widget-google_maps\" data-id=\"d779c9c\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=PaAutos%20-%20Zona%2010%20Guatemala&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"PaAutos - Zona 10 Guatemala\"\n\t\t\t\t\taria-label=\"PaAutos - Zona 10 Guatemala\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-863bac0 e-flex e-con-boxed e-con e-parent\" data-id=\"863bac0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-797b614 e-con-full e-flex e-con e-child\" data-id=\"797b614\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be70112 elementor-widget elementor-widget-heading\" data-id=\"be70112\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Instalaciones de PaAutos Zona 10<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8f5be3 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"c8f5be3\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-4399 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8f5be3\" data-elementor-lightbox-title=\"Zona10_1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkwNSwidXJsIjoiaHR0cHM6XC9cL3BhYXV0b3MuZ3RcL2luaWNpb1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDlcL1pvbmExMF8xLmpwZyIsInNsaWRlc2hvdyI6ImM4ZjViZTMifQ%3D%3D\" href='https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1-300x200.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1-1024x681.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1-768x511.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1.jpg 1198w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8f5be3\" data-elementor-lightbox-title=\"Taller zona 10\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkwNCwidXJsIjoiaHR0cHM6XC9cL3BhYXV0b3MuZ3RcL2luaWNpb1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDlcL1RhbGxlci16b25hLTEwLTEuanBnIiwic2xpZGVzaG93IjoiYzhmNWJlMyJ9\" href='https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-zona-10-1.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-zona-10-1-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-zona-10-1-300x200.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-zona-10-1-1024x684.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-zona-10-1-768x513.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-zona-10-1.jpg 1222w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8f5be3\" data-elementor-lightbox-title=\"Zona10_4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkwOCwidXJsIjoiaHR0cHM6XC9cL3BhYXV0b3MuZ3RcL2luaWNpb1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDlcL1pvbmExMF80LmpwZyIsInNsaWRlc2hvdyI6ImM4ZjViZTMifQ%3D%3D\" href='https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_4.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_4-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_4-300x200.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_4-1024x681.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_4-768x511.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_4.jpg 1198w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8f5be3\" data-elementor-lightbox-title=\"Zona10_2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkwNiwidXJsIjoiaHR0cHM6XC9cL3BhYXV0b3MuZ3RcL2luaWNpb1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDlcL1pvbmExMF8yLmpwZyIsInNsaWRlc2hvdyI6ImM4ZjViZTMifQ%3D%3D\" href='https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_2-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_2-300x200.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_2-1024x681.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_2-768x511.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_2.jpg 1198w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8f5be3\" data-elementor-lightbox-title=\"Zona10_3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkwNywidXJsIjoiaHR0cHM6XC9cL3BhYXV0b3MuZ3RcL2luaWNpb1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDlcL1pvbmExMF8zLmpwZyIsInNsaWRlc2hvdyI6ImM4ZjViZTMifQ%3D%3D\" href='https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_3-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_3-300x200.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_3-1024x681.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_3-768x511.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_3.jpg 1198w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8f5be3\" data-elementor-lightbox-title=\"Zona10_6\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxMCwidXJsIjoiaHR0cHM6XC9cL3BhYXV0b3MuZ3RcL2luaWNpb1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDlcL1pvbmExMF82LmpwZyIsInNsaWRlc2hvdyI6ImM4ZjViZTMifQ%3D%3D\" href='https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_6-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_6-300x200.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_6-1024x681.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_6-768x511.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_6.jpg 1198w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c8f5be3\" data-elementor-lightbox-title=\"Zona10_7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxMSwidXJsIjoiaHR0cHM6XC9cL3BhYXV0b3MuZ3RcL2luaWNpb1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDlcL1pvbmExMF83LmpwZyIsInNsaWRlc2hvdyI6ImM4ZjViZTMifQ%3D%3D\" href='https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_7-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_7-300x200.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_7-1024x681.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_7-768x511.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_7.jpg 1198w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6afbcb2 e-con-full e-flex e-con e-child\" data-id=\"6afbcb2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c03d0bb elementor-widget elementor-widget-heading\" data-id=\"c03d0bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicios de PaAutos Zona 10<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34eb454 elementor-grid-1 elementor-posts--thumbnail-top elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"34eb454\" data-element_type=\"widget\" data-settings=\"{&quot;custom_columns&quot;:&quot;1&quot;,&quot;custom_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;custom_columns_tablet&quot;:&quot;2&quot;,&quot;custom_columns_mobile&quot;:&quot;1&quot;,&quot;custom_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.custom\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t      <div class=\"ecs-posts elementor-posts-container elementor-posts   elementor-grid elementor-posts--skin-custom\" data-settings=\"{&quot;current_page&quot;:1,&quot;max_num_pages&quot;:1,&quot;load_method&quot;:&quot;&quot;,&quot;widget_id&quot;:&quot;34eb454&quot;,&quot;post_id&quot;:4399,&quot;theme_id&quot;:4399,&quot;change_url&quot;:false,&quot;reinit_js&quot;:false}\">\n      \t\t<article id=\"post-3020\" class=\"elementor-post elementor-grid-item ecs-post-loop post-3020 servicio type-servicio status-publish has-post-thumbnail hentry\">\n\t\t\t\t<div data-elementor-type=\"loop\" data-elementor-id=\"3869\" class=\"elementor elementor-3869 post-3020 servicio type-servicio status-publish has-post-thumbnail hentry ast-article-single\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7167e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7167e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c793576\" data-id=\"c793576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ae6db4 elementor-widget elementor-widget-image\" data-id=\"4ae6db4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/paautos.gt\/inicio\/servicio\/llantas\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/10\/Lllantas-1024x612.jpg\" class=\"attachment-large size-large wp-image-3022\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/10\/Lllantas-1024x612.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/10\/Lllantas-300x179.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/10\/Lllantas-768x459.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/10\/Lllantas.jpg 1036w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02254a1\" data-id=\"02254a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab24be1 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ab24be1\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/servicio\/llantas\/\">Venta e Instalaci\u00f3n de Llantas en Guatemala<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article id=\"post-1569\" class=\"elementor-post elementor-grid-item ecs-post-loop post-1569 servicio type-servicio status-publish has-post-thumbnail hentry\">\n\t\t\t\t<div data-elementor-type=\"loop\" data-elementor-id=\"3869\" class=\"elementor elementor-3869 post-1569 servicio type-servicio status-publish has-post-thumbnail hentry ast-article-single\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7167e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7167e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c793576\" data-id=\"c793576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ae6db4 elementor-widget elementor-widget-image\" data-id=\"4ae6db4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/paautos.gt\/inicio\/servicio\/servicio-mayor\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/07\/01.-Servicio-menor-1024x612.jpg\" class=\"attachment-large size-large wp-image-2643\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/07\/01.-Servicio-menor-1024x612.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/07\/01.-Servicio-menor-300x179.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/07\/01.-Servicio-menor-768x459.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/07\/01.-Servicio-menor.jpg 1036w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02254a1\" data-id=\"02254a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab24be1 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ab24be1\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/servicio\/servicio-mayor\/\">Servicio mayor<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article id=\"post-1488\" class=\"elementor-post elementor-grid-item ecs-post-loop post-1488 servicio type-servicio status-publish has-post-thumbnail hentry\">\n\t\t\t\t<div data-elementor-type=\"loop\" data-elementor-id=\"3869\" class=\"elementor elementor-3869 post-1488 servicio type-servicio status-publish has-post-thumbnail hentry ast-article-single\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7167e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7167e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c793576\" data-id=\"c793576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ae6db4 elementor-widget elementor-widget-image\" data-id=\"4ae6db4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/paautos.gt\/inicio\/servicio\/servicio-de-caja-automatica\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/04.-Servicio-de-caja-1024x612.jpg\" class=\"attachment-large size-large wp-image-2647\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/04.-Servicio-de-caja-1024x612.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/04.-Servicio-de-caja-300x179.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/04.-Servicio-de-caja-768x459.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/04.-Servicio-de-caja.jpg 1036w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02254a1\" data-id=\"02254a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab24be1 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ab24be1\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/servicio\/servicio-de-caja-automatica\/\">Servicio de Caja Autom\u00e1tica<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article id=\"post-1487\" class=\"elementor-post elementor-grid-item ecs-post-loop post-1487 servicio type-servicio status-publish has-post-thumbnail hentry\">\n\t\t\t\t<div data-elementor-type=\"loop\" data-elementor-id=\"3869\" class=\"elementor elementor-3869 post-1487 servicio type-servicio status-publish has-post-thumbnail hentry ast-article-single\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7167e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7167e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c793576\" data-id=\"c793576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ae6db4 elementor-widget elementor-widget-image\" data-id=\"4ae6db4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/paautos.gt\/inicio\/servicio\/suspension-y-direccion\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/05.-Tren-delantero-1024x612.jpg\" class=\"attachment-large size-large wp-image-2648\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/05.-Tren-delantero-1024x612.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/05.-Tren-delantero-300x179.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/05.-Tren-delantero-768x459.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/06\/05.-Tren-delantero.jpg 1036w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02254a1\" data-id=\"02254a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab24be1 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ab24be1\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/servicio\/suspension-y-direccion\/\">Suspensi\u00f3n y Direcci\u00f3n<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article id=\"post-832\" class=\"elementor-post elementor-grid-item ecs-post-loop post-832 servicio type-servicio status-publish has-post-thumbnail hentry adicionales-destacar\">\n\t\t\t\t<div data-elementor-type=\"loop\" data-elementor-id=\"3869\" class=\"elementor elementor-3869 post-832 servicio type-servicio status-publish has-post-thumbnail hentry adicionales-destacar ast-article-single\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7167e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7167e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c793576\" data-id=\"c793576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ae6db4 elementor-widget elementor-widget-image\" data-id=\"4ae6db4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/paautos.gt\/inicio\/servicio\/baterias-para-carro\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/07.-Baterias-1024x612.jpg\" class=\"attachment-large size-large wp-image-2652\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/07.-Baterias-1024x612.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/07.-Baterias-300x179.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/07.-Baterias-768x459.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/07.-Baterias.jpg 1036w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02254a1\" data-id=\"02254a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab24be1 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ab24be1\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/servicio\/baterias-para-carro\/\">Bater\u00edas para carro<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article id=\"post-829\" class=\"elementor-post elementor-grid-item ecs-post-loop post-829 servicio type-servicio status-publish has-post-thumbnail hentry\">\n\t\t\t\t<div data-elementor-type=\"loop\" data-elementor-id=\"3869\" class=\"elementor elementor-3869 post-829 servicio type-servicio status-publish has-post-thumbnail hentry ast-article-single\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7167e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7167e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c793576\" data-id=\"c793576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ae6db4 elementor-widget elementor-widget-image\" data-id=\"4ae6db4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/paautos.gt\/inicio\/servicio\/frenos\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/09.-Frenos-1-1024x612.jpg\" class=\"attachment-large size-large wp-image-2661\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/09.-Frenos-1-1024x612.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/09.-Frenos-1-300x179.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/09.-Frenos-1-768x459.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/09.-Frenos-1.jpg 1036w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02254a1\" data-id=\"02254a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab24be1 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ab24be1\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/servicio\/frenos\/\">Frenos<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article id=\"post-826\" class=\"elementor-post elementor-grid-item ecs-post-loop post-826 servicio type-servicio status-publish has-post-thumbnail hentry\">\n\t\t\t\t<div data-elementor-type=\"loop\" data-elementor-id=\"3869\" class=\"elementor elementor-3869 post-826 servicio type-servicio status-publish has-post-thumbnail hentry ast-article-single\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7167e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7167e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c793576\" data-id=\"c793576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ae6db4 elementor-widget elementor-widget-image\" data-id=\"4ae6db4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/paautos.gt\/inicio\/servicio\/servicio-menor\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/11.-Servicio-menor-1024x612.jpg\" class=\"attachment-large size-large wp-image-2660\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/11.-Servicio-menor-1024x612.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/11.-Servicio-menor-300x179.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/11.-Servicio-menor-768x459.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/11.-Servicio-menor.jpg 1036w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02254a1\" data-id=\"02254a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab24be1 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ab24be1\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/servicio\/servicio-menor\/\">Servicio menor<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article id=\"post-825\" class=\"elementor-post elementor-grid-item ecs-post-loop post-825 servicio type-servicio status-publish has-post-thumbnail hentry adicionales-destacar\">\n\t\t\t\t<div data-elementor-type=\"loop\" data-elementor-id=\"3869\" class=\"elementor elementor-3869 post-825 servicio type-servicio status-publish has-post-thumbnail hentry adicionales-destacar ast-article-single\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7167e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7167e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c793576\" data-id=\"c793576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ae6db4 elementor-widget elementor-widget-image\" data-id=\"4ae6db4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/paautos.gt\/inicio\/servicio\/alineacion-3d\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"612\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/13.-Alineacion-1024x612.jpg\" class=\"attachment-large size-large wp-image-2662\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/13.-Alineacion-1024x612.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/13.-Alineacion-300x179.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/13.-Alineacion-768x459.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/05\/13.-Alineacion.jpg 1036w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02254a1\" data-id=\"02254a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab24be1 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ab24be1\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/servicio\/alineacion-3d\/\">Alineaci\u00f3n de llantas 3D<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d36ff7d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d36ff7d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/paautos.gt\/inicio\/servicios\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tools\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VER M\u00c1S SERVICIOS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ae32409 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ae32409\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e620105\" data-id=\"6e620105\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56f8d1f0 elementor-widget elementor-widget-heading\" data-id=\"56f8d1f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros talleres<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-196e3e41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"196e3e41\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1ec09559\" data-id=\"1ec09559\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3967c7cb elementor-widget elementor-widget-heading\" data-id=\"3967c7cb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/ubicaciones\/tienda-zona-9\/\">Taller Zona 10<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cf34a8f elementor-widget elementor-widget-image\" data-id=\"2cf34a8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1-1024x681.jpg\" class=\"attachment-large size-large wp-image-2905\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1-1024x681.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1-300x200.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1-768x511.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Zona10_1.jpg 1198w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3facac16 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3facac16\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/paautos.gt\/inicio\/nuestros-talleres\/taller-zona-10\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VER TALLER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-79da53ee\" data-id=\"79da53ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9275fa0 elementor-widget elementor-widget-heading\" data-id=\"9275fa0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/ubicaciones\/tienda-zona-9\/\">Taller Zona 12<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ea044c elementor-widget elementor-widget-image\" data-id=\"7ea044c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"250\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/07\/paautos-zona-12.jpg\" class=\"attachment-large size-large wp-image-1660\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/07\/paautos-zona-12.jpg 400w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/07\/paautos-zona-12-300x188.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36da0440 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"36da0440\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/paautos.gt\/inicio\/nuestros-talleres\/taller-zona-12\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VER TALLER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4716ded2\" data-id=\"4716ded2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a032e04 elementor-widget elementor-widget-heading\" data-id=\"5a032e04\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/paautos.gt\/inicio\/ubicaciones\/tienda-zona-9\/\">Taller Mateo Flores<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27156a97 elementor-widget elementor-widget-image\" data-id=\"27156a97\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-mateo-flores-1024x684.jpg\" class=\"attachment-large size-large wp-image-2891\" alt=\"\" srcset=\"https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-mateo-flores-1024x684.jpg 1024w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-mateo-flores-300x200.jpg 300w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-mateo-flores-768x513.jpg 768w, https:\/\/paautos.gt\/inicio\/wp-content\/uploads\/2021\/09\/Taller-mateo-flores.jpg 1222w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d62aa10 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6d62aa10\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/paautos.gt\/inicio\/nuestros-talleres\/taller-mateo-flores\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VER TALLER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PaAutos &#8211; Taller Mec\u00e1nico en Zona 10 PaAutos Zona 10 es nuestro nuevo taller mec\u00e1nico y centro automotriz en Ciudad de Guatemala, dise\u00f1ado para ofrecer un servicio r\u00e1pido, eficiente y con la comodidad que necesitas. Contamos con instalaciones amplias, modernas y equipadas, ideales para que tu experiencia sea \u00e1gil y segura mientras realizamos el mantenimiento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":856,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4399","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/paautos.gt\/inicio\/wp-json\/wp\/v2\/pages\/4399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paautos.gt\/inicio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paautos.gt\/inicio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paautos.gt\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paautos.gt\/inicio\/wp-json\/wp\/v2\/comments?post=4399"}],"version-history":[{"count":16,"href":"https:\/\/paautos.gt\/inicio\/wp-json\/wp\/v2\/pages\/4399\/revisions"}],"predecessor-version":[{"id":4458,"href":"https:\/\/paautos.gt\/inicio\/wp-json\/wp\/v2\/pages\/4399\/revisions\/4458"}],"up":[{"embeddable":true,"href":"https:\/\/paautos.gt\/inicio\/wp-json\/wp\/v2\/pages\/856"}],"wp:attachment":[{"href":"https:\/\/paautos.gt\/inicio\/wp-json\/wp\/v2\/media?parent=4399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}